{"id":12358,"date":"2026-05-06T13:41:24","date_gmt":"2026-05-06T16:41:24","guid":{"rendered":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/?p=12358"},"modified":"2026-05-06T13:41:29","modified_gmt":"2026-05-06T16:41:29","slug":"para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta","status":"publish","type":"post","link":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/","title":{"rendered":"Para este jueves rige alerta amarilla por viento Zonda en Salta"},"content":{"rendered":"\n<p>El servicio Meteorol\u00f3gico nacional emiti\u00f3 para este jueves alerta amarilla por viento zonda en distintas zonas de la provincia.<\/p>\n\n\n\n<p>La alerta regir\u00e1 desde las 12 hasta las 18 de ma\u00f1ana con viento Zonda con velocidades entre 30 y 45 km\/h, con r\u00e1fagas que pueden superar los 65 km\/h. Este fen\u00f3meno puede provocar reducci\u00f3n de la visibilidad, un repentino aumento de temperaturas y condiciones muy secas.<\/p>\n\n\n\n<p>Se ver\u00e1 afectada el \u00e1rea de los Valles de Cachi &#8211; Valles de Cafayate &#8211; Valles de Chicoana &#8211; Valles de La Caldera &#8211; Valles de La Poma &#8211; Valles de Molinos &#8211; Valles de Rosario de Lerma &#8211; Valles de San Carlos.<\/p>\n\n\n\n<p>Tambi\u00e9n el \u00e1rea de General Jos\u00e9 de San Mart\u00edn &#8211; Yunga de Iruya &#8211; Yunga de Or\u00e1n &#8211; Yunga de Santa Victoria -Anta &#8211; General G\u00fcemes &#8211; La Candelaria &#8211; Met\u00e1n &#8211; Rosario de la Frontera-Puna de Cachi &#8211; Puna de La Poma &#8211; Puna de Los Andes &#8211; Puna de Molinos-Capital &#8211; Cerrillos &#8211; Guachipas &#8211; La Vi\u00f1a &#8211; Zona baja de Chicoana &#8211; Zona baja de La Caldera &#8211; Zona baja de Rosario de Lerma &#8211; Zona monta\u00f1osa de Cafayate.<\/p>\n\n\n\n<p>En tanto la zona cordillerana ser\u00e1 afectada por vientos del sector oeste con velocidades entre 50 y 70 km\/h con r\u00e1fagas que pueden superar los 90 km\/h.<\/p>\n\n\n\n<p>El resto del \u00e1rea ser\u00e1 afectada por vientos del sudoeste rotando al sur, con velocidades entre 30 y 45 km\/h, con r\u00e1fagas que pueden superar los 65 km\/h.<\/p>\n\n\n\n<p>En este marco se recomienda a la poblaci\u00f3n:<br>1- Evitar salir al momento del fen\u00f3meno.<br>2- Cerrar puertas y ventanas para evitar la entrada de polvo y aire caliente.<br>3- Retirar o asegura objetos que puedan ser arrastrados por el viento, como macetas, sillas o toldos.<br>4- No refugiarse debajo de marquesinas, carteles publicitarios, \u00e1rboles o postes.<br>5- Conducir con precauci\u00f3n.<br>6- Hidratarse y protegerse los ojos y nariz del polvo con anteojos y barbijo.<br>7- No encender fuego.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Fuente:&nbsp;<strong>Secretar\u00eda de Prensa y Comunicaci\u00f3n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El servicio Meteorol\u00f3gico nacional emiti\u00f3 para este jueves alerta amarilla por viento zonda en distintas zonas de la provincia. La alerta regir\u00e1 desde las 12 hasta las 18 de ma\u00f1ana con viento Zonda con velocidades entre 30 y 45 km\/h, con r\u00e1fagas que pueden superar los 65 km\/h. Este fen\u00f3meno puede provocar reducci\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[16],"tags":[1320,100],"class_list":["post-12358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alerta-meteorologico","tag-municipio-de-campo-quijano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9<\/title>\n<meta name=\"description\" content=\"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9\" \/>\n<meta property=\"og:description\" content=\"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/\" \/>\n<meta property=\"og:site_name\" content=\"RQ 99.9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nahuelproducciones999\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T16:41:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T16:41:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-content\/uploads\/2026\/05\/107714-para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-la-provincia-e1778085652547.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Cecilia Pastrana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nahuproduciones\" \/>\n<meta name=\"twitter:site\" content=\"@nahuproduciones\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cecilia Pastrana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/\",\"url\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/\",\"name\":\"Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9\",\"isPartOf\":{\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#website\"},\"datePublished\":\"2026-05-06T16:41:24+00:00\",\"dateModified\":\"2026-05-06T16:41:29+00:00\",\"author\":{\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/e8a4f939e2cb487fe6d0c54042c9d32c\"},\"description\":\"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para este jueves rige alerta amarilla por viento Zonda en Salta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#website\",\"url\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/\",\"name\":\"RQ 99.9\",\"description\":\"Radio Quijano 99.9 MHz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/e8a4f939e2cb487fe6d0c54042c9d32c\",\"name\":\"Cecilia Pastrana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/661a3ef63a8488d4f2794ed44af8cf71420f7e106f3072c40125114df5157749?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/661a3ef63a8488d4f2794ed44af8cf71420f7e106f3072c40125114df5157749?s=96&d=mm&r=g\",\"caption\":\"Cecilia Pastrana\"},\"sameAs\":[\"cecy\"],\"url\":\"https:\/\/nahuelproducciones.com.ar\/radioquijano\/author\/cecy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9","description":"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/","og_locale":"es_ES","og_type":"article","og_title":"Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9","og_description":"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.","og_url":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/","og_site_name":"RQ 99.9","article_publisher":"https:\/\/www.facebook.com\/nahuelproducciones999\/","article_published_time":"2026-05-06T16:41:24+00:00","article_modified_time":"2026-05-06T16:41:29+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-content\/uploads\/2026\/05\/107714-para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-la-provincia-e1778085652547.webp","type":"image\/webp"}],"author":"Cecilia Pastrana","twitter_card":"summary_large_image","twitter_creator":"@nahuproduciones","twitter_site":"@nahuproduciones","twitter_misc":{"Escrito por":"Cecilia Pastrana","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/","url":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/","name":"Para este jueves rige alerta amarilla por viento Zonda en Salta - RQ 99.9","isPartOf":{"@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#website"},"datePublished":"2026-05-06T16:41:24+00:00","dateModified":"2026-05-06T16:41:29+00:00","author":{"@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/e8a4f939e2cb487fe6d0c54042c9d32c"},"description":"El fen\u00f3meno provocar\u00e1 r\u00e1fagas intensas, aumento de temperatura y condiciones secas, por lo que se recomienda a la poblaci\u00f3n extremar las medidas de precauci\u00f3n. Afectar\u00e1 valles, yungas, puna y zona cordillerana a partir de ma\u00f1ana al mediod\u00eda.","breadcrumb":{"@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/para-este-jueves-rige-alerta-amarilla-por-viento-zonda-en-salta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/"},{"@type":"ListItem","position":2,"name":"Para este jueves rige alerta amarilla por viento Zonda en Salta"}]},{"@type":"WebSite","@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#website","url":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/","name":"RQ 99.9","description":"Radio Quijano 99.9 MHz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/e8a4f939e2cb487fe6d0c54042c9d32c","name":"Cecilia Pastrana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/661a3ef63a8488d4f2794ed44af8cf71420f7e106f3072c40125114df5157749?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/661a3ef63a8488d4f2794ed44af8cf71420f7e106f3072c40125114df5157749?s=96&d=mm&r=g","caption":"Cecilia Pastrana"},"sameAs":["cecy"],"url":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/author\/cecy\/"}]}},"_links":{"self":[{"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/posts\/12358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/comments?post=12358"}],"version-history":[{"count":1,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/posts\/12358\/revisions"}],"predecessor-version":[{"id":12360,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/posts\/12358\/revisions\/12360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/media\/12359"}],"wp:attachment":[{"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/media?parent=12358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/categories?post=12358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nahuelproducciones.com.ar\/radioquijano\/wp-json\/wp\/v2\/tags?post=12358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}